{"id":10,"date":"2025-09-11T15:54:06","date_gmt":"2025-09-11T15:54:06","guid":{"rendered":"https:\/\/e-bigfish.com\/bigfishint\/?page_id=10"},"modified":"2026-02-09T14:31:21","modified_gmt":"2026-02-09T14:31:21","slug":"cabinet-de-rh-achats-developpement-humain-big-fish-international","status":"publish","type":"page","link":"https:\/\/e-bigfish.com\/bigfishint\/","title":{"rendered":"Accueil"},"content":{"rendered":"\n<!-- ===== Section Hero TEJ ===== -->\n<section class=\"tej-hero\">\n    <div class=\"tej-bg\" style=\"background-image: url('https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/sham-jallaludin-WIgQqi7_M6o-unsplash-scaled.jpg');\"><\/div>\n    <div class=\"tej-right-vertical\">\n        BiG FISH INTERNATIONAL\n    <\/div>\n    <div class=\"tej-inner\">\n        <h1>\n            BIG FISH INTERNATIONAL\n        <\/h1>\n        <div class=\"tej-tag\">\n            PEOPLE CENTRIC DEVELOPMENT\n        <\/div>\n    <\/div>\n<\/section>\n<!-- ===== Fin de la Section Hero TEJ ===== -->\n\n<!-- ===== SECTION \"PEOPLE CENTRIC\" (AM\u00c9LIOR\u00c9E) ===== -->\n<section id=\"people-centric\" class=\"tej-page-section\">\n    <div class=\"tej-section-container\">\n        <header class=\"section-header\">\n            <h2>PEOPLE CENTRIC DEVELOPMENT<\/h2>\n        <\/header>\n        <div class=\"tej-people-centric-grid\">\n            <div class=\"tej-people-centric-content\">\n                <p>\n                    Notre <span class=\"tej-highlight\">cabinet Ressources Humaines Achats<\/span> se distingue par une approche unique : le d\u00e9veloppement centr\u00e9 sur les personnes (People Centric Development), pour et par les Achats (P&#038;P).\n                <\/p>\n                <p>\n                    Les personnes sont au c\u0153ur de toute r\u00e9ussite. Elles peuvent surmonter n&rsquo;importe quel d\u00e9fi et atteindre des r\u00e9sultats extraordinaires, \u00e0 condition de trouver les moyens de les attirer, de les motiver et de les soutenir.\n                <\/p>\n                <p>\n                    Si vous g\u00e9rez correctement votre <span class=\"tej-highlight\">\u00ab\u00a0capital humain\u00a0\u00bb<\/span>, vous pouvez ajouter des outils et un cadre pour structurer et acc\u00e9l\u00e9rer leur dynamisme ; sinon, ceux-ci auront peu ou pas d&rsquo;impact.\n                <\/p>\n                <p>\n                    Nous vous aidons \u00e0 mettre en \u0153uvre et \u00e0 appliquer une approche \u00ab\u00a0centr\u00e9e sur les personnes\u00a0\u00bb en d\u00e9veloppant votre ou vos \u00e9quipes cl\u00e9s dans le domaine des Achats, ce qui leur permettra \u00e0 leur tour de g\u00e9rer efficacement vos ressources externes.\n                <\/p>\n            <\/div>\n            <div class=\"tej-people-centric-visual\">\n                <div class=\"stickman-wrapper\">\n                    <img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png\" alt=\"Illustration People Centric\">\n                    <div class=\"skill-label skill-knowledge\"><strong>Connaissances<\/strong><\/div>\n                    <div class=\"skill-label skill-soft\"><strong>Personnalit\u00e9<\/strong><\/div>\n                    <div class=\"skill-label skill-value\"><strong>Valeurs<\/strong><\/div>\n                    <div class=\"skill-label skill-comm\"><strong>Communication<\/strong><\/div>\n                    <div class=\"skill-label skill-exp\"><strong>Exp\u00e9rience<\/strong><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<!-- ===== SECTIONS D'OFFRES TEJ (CODE AM\u00c9LIOR\u00c9) ===== -->\n<div class=\"tej-offers-wrapper\">\n\n    <!-- ===== 1. Section \u00c9cosyst\u00e8me ===== -->\n    <section id=\"ecosystem\" class=\"tej-page-section\">\n        <header class=\"section-header\">\n            <h2>Notre \u00e9cosyst\u00e8me<\/h2>\n            <h3>Expertise et sources\/ressources en Achats\/Gestion des ressources externes (ERM)<\/h3>\n        <\/header>\n        <div class=\"ecosystem-container\">\n            <div class=\"eco-card\"><h3>F\u00e9d\u00e9rations et Associations Achats (47+)<\/h3><p><span class=\"highlight\">CIPS &#8211; ISM &#8211; IFPSM (45)<\/span><br>ex. <span class=\"highlight\">CNA<\/span> 22 000 \u2013 <span class=\"highlight\">BME<\/span> 12 000 \u2013 <span class=\"highlight\">NEVI<\/span> 6 000<br>coordination internationale depuis 2024<\/p><\/div>\n            <div class=\"eco-card\"><h3>R\u00e9seau professionnel Achats<\/h3><p>Am\u00e9riques &#8211; Asie &#8211; Europe &#8211; MEA<br>base vivante > 50 000 Acheteurs<br><span class=\"highlight\">croissance organique depuis 2002<\/span><\/p><\/div>\n            <div class=\"eco-card\"><h3>Exp\u00e9rience terrain \u2013 r\u00e9f\u00e9rences<\/h3><p>Am\u00e9rique du Nord &#8211; Afrique &#8211; Asie &#8211; Europe<br>ex. > 300 organisations Corporate et ETI<br>depuis 2002<\/p><\/div>\n            <div class=\"eco-card\"><h3>Passerelles ONGs et Entreprises<\/h3><p>Afrique &#8211; Asie &#8211; Europe<br>ex. Rotary, Bill Gates Foundation, The Barefoot School, Le Moulin du Pont R\u00fb, Young entrepreneurs, Ecole 39<br><span class=\"highlight\">\u00e9change et coop\u00e9ration actifs depuis 2010<\/span><\/p><\/div>\n            <div class=\"center-column\">\n                <a href=\"#assessment\" class=\"pillar-box\" id=\"pillar1\">I. Profilage Cible &#038; <br>Evaluation<\/a>\n                <a href=\"#sourcing\" class=\"pillar-box\" id=\"pillar2\">II. Sourcing de Talent &#038;<br> Recrutement<\/a>\n                <a href=\"#development\" class=\"pillar-box\" id=\"pillar3\">III. D\u00e9veloppement comp\u00e9tences &#038; <br>talent\/\u00e9quipes<\/a>\n                <a href=\"#how-to-make-it-happen\" class=\"pillar-box\" id=\"pillar4\">IV. S\u00e9curiser application et <br>r\u00e9sultat(PCBD)<\/a>\n                <div class=\"circle-core\">\n                    <div class=\"title\">Ecosyst\u00e8me<\/div>\n                    <p class=\"subtitle\">Expertise &#038; M\u00e9thodes<\/p>\n                    <p class=\"subtitle\">Data &#038; Info \u2022 <strong>Cl\u00e9<\/strong> \u2022 32 + 200<\/p>\n                    <div class=\"presence\">Pr\u00e9sence globale (AP, EU, NA, MEA)<\/div>\n                <\/div>\n            <\/div>\n            <div class=\"eco-card\"><h3>Ecoles de Commerce \/ Facult\u00e9s \u00e9conomiques (55 000)<\/h3><p><span class=\"highlight\">AACSB &#8211; AMBA &#8211; EFMD<\/span> (200 &#8211; 2000)<br>ex. <span class=\"highlight\">EQUIS<\/span> (600+)<br>audit &#038; benchmark pour certification depuis 2000<\/p><\/div>\n            <div class=\"eco-card\"><h3>Ecoles et Masters Achats<\/h3><p>Am\u00e9rique du Nord &#8211; Asie Pacifique &#8211; Europe &#8211; Afrique<br>ex. France (39 Masters) &#8211; Allemagne (12+ Masters)<br><span class=\"highlight\">\u00e9change et collaboration depuis 2000<\/span><\/p><\/div>\n            <div class=\"eco-card\"><h3>Passerelles Ecoles et Entreprises<\/h3><p>Afrique &#8211; Asie &#8211; Europe<br>ex. youngtalentfromindia\/youngtalentfromafrica.com<br><span class=\"highlight\">lancement 2024<\/span><\/p><\/div>\n            <div class=\"eco-card\"><h3>Recherche &#038; Pratique<\/h3><p>Am\u00e9rique du Nord &#8211; Asie Pacifique &#8211; Europe<br>ex. IPSERA (r\u00e9seau mondial de chercheurs Achats)<br>comit\u00e9 de r\u00e9daction Excellence HA depuis 2014<\/p><\/div>\n            <div class=\"eco-card\"><h3>Publications et co-publications<\/h3><p>Allemagne \u2013 France \u2013 Pologne \u2013 Japon<\/p>\n                <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/d95bc0_ce6319c6c7b042bebcf371e15c30b2dc~mv2.png\" alt=\"Couvertures des publications\" class=\"publications-image\">\n            <\/div>\n        <\/div>\n    <\/section>\n\n    <!-- ===== 2. Section Assessment ===== -->\n    <section id=\"assessment\" class=\"tej-page-section\">\n        <header class=\"section-header\">\n            <h2>I. Profilage cible &#038; Evaluation 360\u00b0<\/h2>\n            <h3>Nouveaux profils et comp\u00e9tences Achats \u2013 focus \u00ab business stakeholders \u00bb et impact<\/h3>\n        <\/header>\n        <div class=\"assessment-canvas\">\n            <div id=\"relationship-card\" class=\"node index-card\"><h4>Relationnel (Indice)<\/h4><p>ex. identification des gaps de perception d&rsquo;action et de capacit\u00e9 d&rsquo;engagement, <span class=\"highlight\">capacit\u00e9 et profil pour individus et \u00e9quipes<\/span><\/p><\/div>\n            <div id=\"diversity-card\" class=\"node index-card\"><h4>Diversit\u00e9 (Indice)<\/h4><p>ex. multiculturel, secteur, categories et domaines, exp\u00e9rience, influence<span class=\"highlight\">fit et potentiel entre march\u00e9s amont et aval<\/span><\/p><\/div>\n            <div id=\"cri-card\" class=\"node index-card\"><h4>CRI<\/h4><p>Client Relationship Index<\/p><\/div>\n            <div id=\"sri-card\" class=\"node index-card\"><h4>SRI<\/h4><p>Supplier Relationship Index<\/p><\/div>\n            <div id=\"collab-card\" class=\"node index-card\"><h4>Collaboration &#038; Innovation (Indice)<\/h4><p>Ex. capacit\u00e9 et profil prioritaire pour d\u00e9velopper et g\u00e9rer collaboration et innovation, <span class=\"highlight\">capacit\u00e9 et profil pour individus et \u00e9quipes<\/span><\/p><\/div>\n            <div id=\"impact-card\" class=\"node index-card\"><h4>Impact (Indice)<\/h4><p>ex. capacit\u00e9 de cr\u00e9ation d\u2019impact pour capacit\u00e9 de cr\u00e9ation de valeur durable<span class=\"highlight\">capacit\u00e9 et profil pour individus et \u00e9quipes<\/span><\/p><\/div>\n            <div id=\"clients-circle\" class=\"node main-circle\">Clients<\/div>\n            <div id=\"suppliers-circle\" class=\"node main-circle\">Fournisseurs<\/div>\n            <div id=\"c-skill-1\" class=\"node skill-bubble\">Ecouter &#038; comprendre<\/div>\n            <div id=\"c-skill-2\" class=\"node skill-bubble\">Cr\u00e9er une solution de valeur ajout\u00e9e<\/div>\n            <div id=\"c-skill-3\" class=\"node skill-bubble\">Communiquer &#038; Convaincre<\/div>\n            <div id=\"c-skill-4\" class=\"node skill-bubble\">S&rsquo;engager &#038; Attenidre des R\u00e9sultats<\/div>\n            <div id=\"s-skill-1\" class=\"node skill-bubble\">Ecouter &#038; comprendre<\/div>\n            <div id=\"s-skill-2\" class=\"node skill-bubble\">Cr\u00e9er une solution de valeur ajout\u00e9e<\/div>\n            <div id=\"s-skill-3\" class=\"node skill-bubble\">Communiquer &#038; Convaincre<\/div>\n            <div id=\"s-skill-4\" class=\"node skill-bubble\">S&rsquo;engager &#038; Attenidre des R\u00e9sultats<\/div>\n            <div id=\"line-team-clients\" class=\"node line connector\"><\/div>\n            <div id=\"line-team-suppliers\" class=\"node line connector\"><\/div>\n            <div id=\"label-perception-clients\" class=\"node label\">Perception<\/div>\n            <div id=\"label-sw-clients\" class=\"node label perception-label\">forces \/ faiblesses<\/div>\n            <div id=\"label-perception-suppliers\" class=\"node label\">Perception<\/div>\n            <div id=\"label-sw-suppliers\" class=\"node label perception-label\">forces \/ faiblesses<\/div>\n            <div id=\"tosca-container\" class=\"node\">\n                <div class=\"tosca-box\"><h4>TOSCA<\/h4><p>Target Oriented Skills Calibrator<\/p><\/div>\n                <div class=\"skills-branches\"><div class=\"skill-box\">Hard Skills<\/div><div class=\"skill-box\">Soft Skills<\/div><div class=\"skill-box\">Activities<\/div><\/div>\n                <div id=\"buyers-circle\" class=\"main-circle\">Acheteurs<div id=\"arrow-from-buyers\" class=\"arrow-down\"><\/div><\/div>\n                <div id=\"team-circle\" class=\"main-circle\">Equipe Achats<\/div>\n            <\/div>\n            <div id=\"benchmark-visual-container\">\n                <div class=\"funnels-container\">\n                    <div class=\"funnel-group\"><div class=\"funnel\">Client Transformation Program<\/div><div class=\"funnel-arrow\"><\/div><\/div>\n                    <div class=\"funnel-group\"><div class=\"funnel\">Organizational &#038; Individual Assessments<\/div><div class=\"funnel-arrow\"><\/div><\/div>\n                    <div class=\"funnel-group\"><div class=\"funnel\">Supplier Transformation Programs<\/div><div class=\"funnel-arrow\"><\/div><\/div>\n                <\/div>\n                <div class=\"benchmark-bar\">Benchmarking<\/div>\n                <table>\n                    <thead>\n                        <tr><th>Sector<\/th><th>Oil &#038; Gas<\/th><th>Basic Material<\/th><th>Industrials<\/th><th>Consumer Goods<\/th><th>Healthcare<\/th><th>Consumer Services<\/th><th>Telecommunication<\/th><th>Utilities<\/th><th>Financials<\/th><th>Technology<\/th><\/tr>\n                    <\/thead>\n                    <tbody>\n                        <tr><td><strong>Clients<\/strong><\/td><td>16<\/td><td>36<\/td><td>17<\/td><td>61<\/td><td>20<\/td><td>4<\/td><td>6<\/td><td>12<\/td><td>12<\/td><td>10<\/td><\/tr>\n                        <tr><td><strong>People<\/strong><\/td><td>7964<\/td><td>5223<\/td><td>5222<\/td><td>3961<\/td><td>5886<\/td><td>4318<\/td><td>6012<\/td><td>9611<\/td><td>8692<\/td><td>7730<\/td><\/tr>\n                    <\/tbody>\n                <\/table>\n            <\/div>\n        <\/div>\n    <\/section>\n\n    <!-- ===== 3. Section Sourcing ===== -->\n    <section id=\"sourcing\" class=\"tej-page-section\">\n        <header class=\"section-header\">\n            <h2>II. Sourcing de Talent &#038; Recrutement<\/h2>\n            <h3>Attraction et r\u00e9tention des talents pour le d\u00e9veloppement des \u00e9quipes<\/h3>\n        <\/header>\n        <div class=\"content-grid\">\n            <div class=\"cards-column\">\n                <div class=\"card\"><h3>Profilage fonctionnel<\/h3><h4>TOR (target-oriented recruitment)<\/h4><p>qualification et d\u00e9finition de profils orient\u00e9s r\u00e9sultats + potentiel<\/p><\/div>\n                <div class=\"card\"><h3>D\u00e9finition du pitch d&rsquo;attraction<\/h3><h4>Donner envie de venir et de rester<\/h4><p>d\u00e9veloppement de cadre et communication orient\u00e9s talents<\/p><\/div>\n                <div class=\"card\"><h3>Speed Recruitment<\/h3><h4>Apprendre \u00e0 attirer et recruter<\/h4><p>Session collective avec Responsables Achats et candidats<\/p><\/div>\n            <\/div>\n            <div class=\"center-column\">\n                <div class=\"strategy-box\"><ul><li>1. Attract<\/li><li>2. Recruit<\/li><li>3. Develop &#038; Retain<\/li><li>4. Give &#038; Take<\/li><\/ul><\/div>\n                <div class=\"recruitment-type\">\n                    <div class=\"type-box\">Permanent<\/div>\n                    <div class=\"person-icon\">\n                        <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/d95bc0_290b203dbc2d41b2afef00ed81a43868~mv2.png\" alt=\"Ic\u00f4ne Acheteurs\">\n                        <span>Acheteurs<\/span>\n                    <\/div>\n                    <div class=\"type-box\">Temporaire<\/div>\n                <\/div>\n            <\/div>\n            <div class=\"cards-column\">\n                <div class=\"card\"><h3>Code-sharing de haut-potentiels<\/h3><h4>G\u00e9rer un \u00e9cosyst\u00e8me de talents<\/h4><p>Cr\u00e9er une ou plusieurs alliances (informelles) d\u2019\u00e9volution et de r\u00e9tention de talents \u00e0 haut potentiel<\/p><\/div>\n                <div class=\"card\"><h3>Agence de gestion de carri\u00e8re<\/h3><h4>D\u00e9veloppement de carri\u00e8re pour vos talents<\/h4><p>Utiliser expertise globale externe pour conseiller et accompagner vos talents en sus de l\u2019action interne<\/p><\/div>\n                <div class=\"card\"><h3>Generation Z<\/h3><h4>KIRIKOU<\/h4><p>Int\u00e9grer et favoriser la dynamique des jeunes professionnels pour d\u00e9velopper et cr\u00e9er un impact r\u00e9el<\/p><\/div>\n            <\/div>\n        <\/div>\n        <footer class=\"sourcing-footer\">\n            <p>Les d\u00e9fis \u00ab <strong>Ressources Humaines<\/strong> \u00bb \u00e0 travers les g\u00e9n\u00e9rations et dans un contexte international \u00e9volutifs requi\u00e8rent des initiatives multiples pour d\u00e9velopper et maintentir un avantage comp\u00e9titif en termes des \u00ab <strong>people<\/strong> \u00bb (internes comme <span class=\"highlight-red\">externes<\/span>)<\/p>\n        <\/footer>\n    <\/section>\n\n    <!-- ===== 4. Section D\u00e9veloppement ===== -->\n    <section id=\"development\" class=\"tej-page-section\">\n        <header class=\"section-header\">\n            <h2>III. D\u00e9veloppement de comp\u00e9tences, talents et \u00e9quipes<\/h2>\n            <h3>Apprendre en performant &#8211; apprendre avec focus et action cr\u00e9ation de valeur<\/h3>\n        <\/header>\n        <div class=\"content-grid\">\n            <div class=\"card\"><h3>Business Partners<\/h3><h4>Leadership Achats<\/h4><p>d\u00e9veloppement de relation et action \u00ab Business Partners \u00bb avec des parties prenantes internes<\/p><\/div>\n            <div class=\"card\"><h3>Innovation &#038; changement paradigme<\/h3><h4>Mission impossible<\/h4><p>apprentissage collectif (avec ou sans externes) sur la base d\u2019un d\u00e9fi r\u00e9el ou choisi avec approche transverse<\/p><\/div>\n            <div class=\"card\"><h3>Mesure de la performance<\/h3><h4>De la \u00ab\u00a0bottom line\u00a0\u00bb \u00e0 la \u00ab\u00a0top line\u00a0\u00bb<\/h4><p>\u00c9laboration collective d\u2019un manuel de mesure de performance avec d\u00e9finition et d\u00e9veloppement de KPIs et m\u00e9thode de mesure\/validation<\/p><\/div>\n            <div class=\"card\"><h3>Communication pour Management<\/h3><h4>Outillage et m\u00e9thode de gestion<\/h4><p>d\u00e9veloppement d\u2019un tableau individuel de communication avec les parties prenantes internes et externes<\/p><\/div>\n            <div class=\"card\"><h3>Communication pour Management<\/h3><h4>Techniques de communication orale<\/h4><p>Apprentissage collectif pratique de techniques de communication pour un contexte d\u2019Achats et d\u2019Acheteurs<\/p><\/div>\n            <div class=\"card\"><h3>Ecosyst\u00e8mes collaboratifs<\/h3><h4>D\u00e9veloppement et Gestion<\/h4><p>Apprentissage pratique de la mise en place et de la gestion d\u2019une initiative ou d\u2019un \u00e9cosyst\u00e8me collaboratifs<\/p><\/div>\n            <div class=\"card\"><h3>D\u00e9veloppement de Talent et Equipes<\/h3><h4>Le manuel pour Acheteurs et Managers Achats \u00e0 potentiel<\/h4><p>d\u00e9veloppement d\u2019action et d\u2019\u00e9volution structur\u00e9es le long des 5 \u00e9tapes du manuel Progr\u00e8s et Impact<\/p><\/div>\n            <div class=\"card\"><h3>D\u00e9veloppement de Talent et Equipes<\/h3><h4>TOCAM &#038; PPD<\/h4><p>d\u00e9veloppement autonome ou guid\u00e9 d\u2019orientation et d\u2019\u00e9volution continues d\u2019un acheteur \/ responsable Achats<\/p><\/div>\n            <div class=\"card\"><h3>D\u00e9veloppement et Partage Expertise<\/h3><h4>Co-\u00e9laboration et -publication<\/h4><ul><li>Dossiers de recherche<\/li><li>Regards crois\u00e9s<\/li><li>Dossiers praticiens terrain<\/li><li>Benchmark &#038; Comparaison<\/li><\/ul><\/div>\n        <\/div>\n        <footer class=\"development-footer\">\n            <p>D\u00e9veloppement collectif ou individuel de la compr\u00e9hension et des comp\u00e9tences \u00ab terrain \u00bb pour une cr\u00e9ation de valeur durable et une \u00e9volution &#038; valorisation individuelle et collective<\/p>\n        <\/footer>\n    <\/section>\n\n    <!-- ===== 5. Section Application ===== -->\n    <section id=\"how-to-make-it-happen\" class=\"tej-page-section\">\n        <div class=\"main-container\">\n            <header class=\"section-header\">\n                <h2>IV. S\u00e9curiser application et impact<\/h2>\n                <h3>D\u00e9veloppement \u00ab bottom up \u00bb (people centric business development)<\/h3>\n            <\/header>\n            <div class=\"resources-visual\">\n                <div class=\"connection-line\"><\/div>\n                <div class=\"resource-group\">\n                    <h3>Ressources<br>internes<\/h3>\n                    <div class=\"circles-container internal-circles\">\n                        <div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div><div class=\"circle internal-circle\"><\/div>\n                    <\/div>\n                    <div class=\"fraction\">1\/4<\/div>\n                <\/div>\n                <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/d95bc0_290b203dbc2d41b2afef00ed81a43868~mv2.png\" alt=\"Achats\" class=\"person-icon\">\n                <div class=\"resource-group\">\n                    <h3>Ressources<br>externes<\/h3>\n                    <div class=\"circles-container external-circles\">\n                        <div class=\"circle external-circle-red\"><\/div><div class=\"circle external-circle-green\"><\/div><div class=\"circle external-circle-yellow\"><\/div><div class=\"circle external-circle-red\"><\/div><div class=\"circle external-circle-green\"><\/div><div class=\"circle external-circle-yellow\"><\/div>\n                    <\/div>\n                    <div class=\"fraction\">3\/4<\/div>\n                <\/div>\n            <\/div>\n            <div class=\"content-grid\">\n                <div class=\"grid-column\">\n                    <div class=\"section-number\">1.<\/div>\n                    <p class=\"point-description\">Implication et d\u00e9veloppement &#8211; valorisation des \u00ab people \u00bb d\u00e8s le d\u00e9but et au-del\u00e0 du terme d\u2019un projet.<\/p>\n                    <div class=\"example-card\"><h3>exemple de projet<br>A\u00e9ronautique \/ D\u00e9fense <span style=\"font-weight:400;\">(scope monde)<\/span><\/h3><p>Avantage comp\u00e9titif via <strong>Leadership Achats<\/strong> et <strong>Gestion<\/strong> de ressources et de projets <strong>collaborative<\/strong>.<\/p><\/div>\n                    <div class=\"example-card\"><h3>exemple de projet<br>FMCG <span style=\"font-weight:400;\">(scope monde)<\/span><\/h3><p>Innovation &#038; Optimisation Co\u00fbt total via <strong>Forge de Talents<\/strong> et <strong>Profil Diversit\u00e9<\/strong> de comp\u00e9tences et parcours.<\/p><\/div>\n                <\/div>\n                <div class=\"grid-column\">\n                    <div class=\"section-number\">2.<\/div>\n                    <p class=\"point-description\">Les \u00ab people \u00bb <strong>internes<\/strong> et <strong>externes<\/strong> ont une large <strong>expertise collective<\/strong> pour trouver et r\u00e9aliser des solutions requises aux d\u00e9fis.<\/p>\n                    <div class=\"example-card\"><h3>exemple de projet<br>Produits &#038; Services <span style=\"font-weight:400;\">(scope monde)<\/span><\/h3><p><strong>Master of International Purchasing (MIP)<\/strong><br>Le meilleur des deux mondes<br><strong>Acad\u00e9mie et Pratique<\/strong>.<\/p><\/div>\n                    <div class=\"example-card\"><h3>exemple de projet<br>Automotive <span style=\"font-weight:400;\">(scope monde)<\/span><\/h3><p>Avantage comp\u00e9titif via approche structur\u00e9e de <strong>collaboration transverse interne et externe (M\u00e9thode 5L)<\/strong>.<\/p><\/div>\n                <\/div>\n            <\/div>\n            <div class=\"chart-section\">\n                <h3>spend %age of turnover<\/h3>\n                <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/d95bc0_0b03b41e8cb0456d92f6e312facbc1a6~mv2.png\" alt=\"Graphique montrant l'\u00e9volution du spend percentage of turnover\" class=\"chart-image\">\n            <\/div>\n        <\/div>\n    <\/section>\n\n    <!-- ===== 6. Section B52K-LAB ===== -->\n    <section id=\"b52k-lab\" class=\"tej-page-section\">\n        <div class=\"main-container\">\n            <header class=\"section-header\">\n                <h2>V. B52K-LAB<\/h2>\n                <h3>Le label qui fait parler votre offre \u00e0 l\u2019oreille des acheteurs.<\/h3>\n            <\/header>\n            <div class=\"b52k-grid\">\n                <div class=\"b52k-media\">\n                    <img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-17-sept.-2025-15_47_34.png\" alt=\"Nuage de mots B52K-LAB : communaut\u00e9, confiance, label, 52k acheteurs\" class=\"b52k-image\">\n                    <div class=\"b52k-badge\">B52K-LAB<\/div>\n                <\/div>\n                <div class=\"b52k-content\">\n                    <p class=\"b52k-intro\">\n                        B52k-Lab est un <strong>laboratoire d\u2019\u00e9valuation de solutions march\u00e9 pour la Communaut\u00e9 Acheteurs<\/strong>.\n\nAvec l\u2019expertise de l\u2019\u00e9quipe cl\u00e9 et des panels d\u2019Acheteurs cat\u00e9gories et projets nous \u00e9valuons et pr\u00e9qualifions des solutions innovantes et productives selon les pratiques et un r\u00e9f\u00e9rentiel de la Communaut\u00e9 Acheteurs.\n\nAvec diff\u00e9rents niveaux et s\u00e9quences d\u2019\u00e9valuation, r\u00e9alis\u00e9e en mode Lab et sur le terrain, nous permettons d\u2019identifier et de pr\u00e9qualifier les solutions march\u00e9, <strong>ayant un caract\u00e8re innovant et productif<\/strong>, permettant \u00e0 la Communaut\u00e9 Acheteurs \u00e0 la fois de participer \u00e0 l\u2019\u00e9valuation des solutions d\u2019un int\u00e9r\u00eat g\u00e9n\u00e9ral ou sp\u00e9cifique \u00e0 travers les diff\u00e9rentes sous-cat\u00e9gories s\u00e9lectionn\u00e9es et de constituer un panel de solutions ad\u00e9quates pour future comparaison et possible utilisation efficace par les Acheteurs de la Communaut\u00e9.\n\nCette approche permet \u00e9galement \u00e0 des fournisseurs de solutions, portant un int\u00e9r\u00eat sur une approche proactive vis-\u00e0-vis de la Communaut\u00e9 Acheteurs, de mieux \u00e9valuer la comp\u00e9titivit\u00e9 de leurs solutions et de pouvoir se positionner dans une d\u00e9marche d\u2019am\u00e9lioration continue dans une d\u00e9marche positive et collaborative avec les Acheteurs en tant que coordinateurs de l\u2019innovation et de la productivit\u00e9 externe.\n                    <\/p>\n                    <p>\n                        Notre \u00e9quipe d\u2019experts Achats et les repr\u00e9sentants de nos panels Acheteurs \u00e9valuent, en \u00e9change continu avec la Communaut\u00e9 Acheteurs, les solutions march\u00e9 dans des cat\u00e9gories et sous-cat\u00e9gories cl\u00e9 pour identifier, filtrer et pr\u00e9qualifier les meilleurs solutions permettant \u00e0 la Communaut\u00e9 Acheteurs de disposer d\u2019un acc\u00e8s efficace et rapide \u00e0 un panel de solutions \u00ab pr\u00e9-test\u00e9es \u00bb, permettant d\u2019acc\u00e9l\u00e9rer le \u00ab time to market interne \u00bb et la qualit\u00e9 des \u00e9changes ult\u00e9rieurs avec les fournisseurs pr\u00e9qualifi\u00e9s dans un but d\u2019optimiser la cr\u00e9ation de valeur des Acheteurs via \u00e0 vis leur d\u00e9fis entreprises et clients internes.\n                    <\/p>\n                    <ul class=\"b52k-features\">\n                        <li>Acc\u00e8s \u00e0 une s\u00e9lection de solutions march\u00e9 pr\u00e9qualifi\u00e9es selon un r\u00e9f\u00e9rentiel int\u00e9gral Acheteur<\/li>\n                        <li>Participation \u00e0 des \u00e9valuations de solutions march\u00e9 innovantes et\/ou productives<\/li>\n                        <li>Echange d\u2019exp\u00e9rience et\/ou benchmarking de solutions avec d\u2019autres Acheteurs<\/li>\n                        <li>Facilit\u00e9 de d\u00e9veloppement \u00e0 l\u2019innovation externe et \u00e0 la cr\u00e9ation de valeur Achats<\/li>\n                    <\/ul>\n                    <div class=\"b52k-cta\">\n                        <a href=\"\/prendre-rendez-vous\/\" class=\"button-ecosystem\">En savoir plus<\/a>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        <!-- JSON-LD (schema.org) pour le SEO -->\n        <script type=\"application\/ld+json\">\n        {\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"Service\",\n            \"name\": \"B52K-LAB\",\n            \"description\": \"Laboratoire d'accompagnement Go To Market et label certifiant l'ad\u00e9quation de l'offre avec la communaut\u00e9 d'acheteurs (52 000 acheteurs).\",\n            \"provider\": {\n                \"@type\": \"Organization\",\n                \"name\": \"Big Fish International\"\n            },\n            \"serviceType\": \"Go To Market Strategy\",\n            \"url\": \"<?php echo esc_url( home_url( '\/#b52k-lab' ) ); ?>\"\n        }\n        <\/script>\n    <\/section>\n\n<\/div>\n<br><br>\n<!-- ===== NOUVELLES SECTIONS TEJ (AM\u00c9LIOR\u00c9ES) ===== -->\n<div class=\"tej-additional-content\">\n\n    <!-- ===== SECTION \"ILS NOUS FONT CONFIANCE\" ===== -->\n    <section id=\"trust\" class=\"tej-page-section\">\n        <div class=\"tej-section-container\">\n            <header class=\"section-header\">\n                <h2 style=\"text-align: left;\">ILS NOUS FONT CONFIANCE<\/h2>\n            <\/header>\n            <div class=\"tej-trust-logos\">\n                <img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Work-industrie-Big-Fish.png\" alt=\"Logos des clients qui nous font confiance\">\n            <\/div>\n        <\/div>\n    <\/section>\n    <br><br><br>\n    <!-- ===== SECTION \"\u00c0 PROPOS\" ===== -->\n    <section id=\"about\" class=\"tej-page-section tej-about-section\">\n        <div class=\"tej-about-grid\">\n            <div class=\"tej-about-content\">\n                <h2>Qui sommes-nous ?<\/h2>\n                <p>Nous sommes le n\u00b01 cabinet ind\u00e9pendant franco-europ\u00e9en sp\u00e9cialis\u00e9s dans le d\u00e9veloppement des personnes et des \u00e9quipes dans le domaine des Achats (gestion des ressources externes).<\/p>\n                <p>Notre cabinet op\u00e8re \u00e0 l&rsquo;\u00e9chelle mondiale depuis 2003 et compte plus de 300 r\u00e9f\u00e9rences d&rsquo;entreprises dans tous les secteurs et toutes les r\u00e9gions. Notre r\u00e9seau d&rsquo;experts et de comp\u00e9tences regroupe plus de 50 000 professionnels des Achats occupant des fonctions et des niveaux d&rsquo;expertise tr\u00e8s vari\u00e9s. Nous \u00e9valuons les organisations et les \u00e9quipes, recherchons et formons des talents, des \u00e9quipes et des organisations, et g\u00e9rons la mise en \u0153uvre r\u00e9ussie de projets commerciaux et de programmes de transformation centr\u00e9s sur les personnes, en mettant l&rsquo;accent \u00e0 la fois sur les r\u00e9sultats financiers et le chiffre d&rsquo;affaires.<\/p>\n                \n                <h3>Notre priorit\u00e9 :<\/h3>\n                <ul>\n                    <li>Notre savoir-faire repose sur plus de 20 ans d&rsquo;exp\u00e9rience internationale en gestion des ressources humaines et des fournisseurs, et sur le constat que vos collaborateurs :<\/li>\n                    <li>sont au c\u0153ur de toute r\u00e9ussite au sein de votre organisation et de votre entreprise<\/li>\n                    <li>doivent s&rsquo;appuyer sur la diversit\u00e9 des profils, la sensibilisation des parties prenantes et la bonne combinaison de comp\u00e9tences techniques et relationnelles pour se concentrer sur l&rsquo;impact commercial<\/li>\n                    <li>doivent \u00eatre impliqu\u00e9s d\u00e8s le d\u00e9but et tout au long d&rsquo;une initiative afin de garantir une appropriation totale et une mise en \u0153uvre pratique<\/li>\n                <\/ul>\n                <p>En collaboration avec vos principaux fournisseurs, nous disposons d&rsquo;une vaste expertise combin\u00e9e qui nous permet de vous proposer des suggestions et des solutions pour relever tous types de d\u00e9fis et obtenir des r\u00e9sultats tangibles et durables.<\/p>\n                \n                <h3>Notre approche :<\/h3>\n                <p>Nous vous aidons \u00e0 concr\u00e9tiser vos projets avec vos \u00e9quipes existantes et quelques \u00ab ingr\u00e9dients \u00bb externes, en g\u00e9rant des projets couronn\u00e9s de succ\u00e8s et en atteignant les r\u00e9sultats escompt\u00e9s tout en d\u00e9veloppant vos ressources humaines, vos comp\u00e9tences et vos \u00e9cosyst\u00e8mes.<\/p>\n                \n                <a href=\"#schedule\" class=\"button-primary-glass\">NOUS REJOINDRE<\/a>\n            <\/div>\n            <div class=\"tej-about-image-wrapper\">\n                <img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/susan-wilkinson-xt39M21pFdQ-unsplash-scaled.jpg\" alt=\"Notre \u00e9quipe en r\u00e9union\">\n            <\/div>\n        <\/div>\n    <\/section>\n    <br><br><br>\n    <!-- ===== SECTION \"\u00c9QUIPE\" ===== -->\n    <section id=\"team\" class=\"tej-page-section\">\n        <div class=\"tej-section-container\">\n            <header class=\"section-header\">\n                <h2>Notre \u00e9quipe<\/h2>\n            <\/header>\n            <div class=\"tej-team-grid\">\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250820_1352_Avatar-Artstyle-Conversion_remix_01k33rfpt1exm8hfs4fc6pa34a.png\" alt=\"Nicolas\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Nicolas<\/p>\n                        <p class=\"member-title\">The Driver<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250815_1325_Avatar-Style-Portrait_remix_01k2ptyyz3fxftwbzd77cd0qha.png\" alt=\"Anna\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Anna<\/p>\n                        <p class=\"member-title\">The Hunter<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250815_1330_Avatar-Art-Style-Portrait_remix_01k2pv8wreechrd0hqmchtcqta-3.png\" alt=\"Sebastien\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Sebastien<\/p>\n                        <p class=\"member-title\">The Developer<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250817_1716_Avatar-Style-Portrait_remix_01k2wd0ngde4hvcy59mhae1dk3.png\" alt=\"Agnieszka\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Agnieszka<\/p>\n                        <p class=\"member-title\">The Warrior<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250815_1333_Avatar-Inspired-Portrait_remix_01k2pve1rrfsxsnsvkef4srvje-2.png\" alt=\"Emmanuel\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Emmanuel<\/p>\n                        <p class=\"member-title\">The DigiMaster<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250819_1026_Avatar-Artstyle-Portrait_remix_01k30tanhtexxazheeh2f32ffx.png\" alt=\"JP\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">JP<\/p>\n                        <p class=\"member-title\">The Transformer<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250824_2009_Avatar-Art-Style-Portrait_remix_01k3eqnzw3f8dsa1weq6ggdpc6.png\" alt=\"Julien\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Julien<\/p>\n                        <p class=\"member-title\">The Architect<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250817_1714_Avatar-Style-Portrait_remix_01k2wcwwcmekh8hb4vvck619sn.png\" alt=\"Abdel\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Abdel<\/p>\n                        <p class=\"member-title\">The Walker<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250819_1019_Avatar-Style-Portrait_remix_01k30syg7ff599kr7nn95dtp4w.png\" alt=\"Janice\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Janice<\/p>\n                        <p class=\"member-title\">The Artist<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250821_1011_Avatar-Style-Portrait_remix_01k35y8p5fefnvr00jg04pnz30.png\" alt=\"Fabien\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Fabien<\/p>\n                        <p class=\"member-title\">The Professor<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250923_1743_Avatar-Style-Portrait_remix_01k5vq7pgvfmn9n4qmk05syxgc.png\" alt=\"Nouveau Membre 13\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Daniel<\/p>\n                        <p class=\"member-title\">The Strategist<\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1241_Avatar-Inspired-Office-Scene_remix_01k5e9yxhmen88rhjq2b85v9gh.png\" alt=\"Nouveau Membre 12\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Nawab<\/p>\n                        <p class=\"member-title\">The Tiger<\/p>\n                    <\/div>\n                <\/div>\n\n              <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/11\/20251022_1710_Airbender-Artstyle-Portrait_remix_01k86awfwweg7a7nabq4ve3ydx.png\" alt=\"NOUVEAU MEMBRE 13\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Yann<\/p>\n                        <p class=\"member-title\">TCB Musician<\/p>\n                    <\/div>\n                <\/div>\n\n<div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/11\/20251104_0840_Avatar-Inspired-Character-Design_remix_01k970avbeew2rt2yabg5h2dhc.png\" alt=\"NOUVEAU MEMBRE 14\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Kevine<\/p>\n                        <p class=\"member-title\">KG7<\/p>\n                    <\/div>\n                <\/div>\n<div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2026\/02\/20260203_0938_Image-Generation_remix_01kghdvsrdeqcb8yzv68v2mn4m.png\" alt=\"NOUVEAU MEMBRE 15\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Yrsa<\/p>\n                        <p class=\"member-title\">Antenna<\/p>\n                    <\/div>\n                <\/div>\n\n              <\/div>\n\n\n   <br><br><br>\n              <div class=\"tej-team-grid\">\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1444_Avatar-Inspired-Pilot-Portrait_remix_01k5egzyvwejtvqkayv10qafq9.png\" alt=\"Nouveau Membre 1\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Sergio<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1418_Airbender-Artstyle-Portrait_remix_01k5efgzazfnds5syd7tb9mvxx.png\" alt=\"Nouveau Membre 2\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Bogdana<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1203_Avatar-Style-Portrait_remix_01k5e7tjb3esks6rrtc6ngqyc6.png\" alt=\"Nouveau Membre 3\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Oksana<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1427_Avatar-Art-Style-Portrait_remix_01k5eg11n1fjn867d2tp7f2npw.png\" alt=\"Nouveau Membre 4\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Valentina<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1406_Airbender-Art-Style-Avatar_remix_01k5eevdmmfg4a1gw2fr37zmh3.png\" alt=\"Nouveau Membre 5\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Olena<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1316_Avatar-Art-Style-Portrait_remix_01k5ebz6kaem79ec06mne4bt53.png\" alt=\"Nouveau Membre 6\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Natalia<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1258_Avatar-Artstyle-Transformation_remix_01k5eaxzwxehz8h354p874xn02.png\" alt=\"Nouveau Membre 7\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Dmytro<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1250_Avatar-Artstyle-Transformation_remix_01k5eagcb4f0qr5ydyd4482sqe.png\" alt=\"Nouveau Membre 8\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Marta<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250918_1248_Avatar-Art-Style_remix_01k5eabbzyfg98401asznyxqq8.png\" alt=\"Nouveau Membre 9\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Inna<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250917_1438_Avatar-Inspired-Portrait_remix_01k5by8vhjf4p9fbjnbjgnr8hs-1.png\" alt=\"Nouveau Membre 10\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Oleksandr<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"team-member-card\">\n                    <div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/20250917_1346_Avatar-Inspired-Portrait_remix_01k5bvamkeek9rmk3qhez8jb3k.png\" alt=\"Nouveau Membre 11\"><\/div>\n                    <div class=\"member-info\">\n                        <p class=\"member-name\">Yan<\/p>\n                        <p class=\"member-title\"><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n    <!-- ===== SECTION \"PLANIFIER UN RENDEZ-VOUS\" (AM\u00c9LIOR\u00c9E) ===== -->\n    <section id=\"schedule\" class=\"tej-page-section tej-schedule-section\">\n        <div class=\"tej-section-container\">\n            <header class=\"section-header\">\n                <h2>Pr\u00eat \u00e0 transformer vos \u00e9quipes ?<\/h2>\n            <\/header>\n            <p>Vous souhaitez \u00e9changer avec nous ?<br>B\u00e9n\u00e9ficiez d\u2019un diagnostic rapide de vos enjeux RH Achats.<\/p>\n            <a href=\"\/prendre-rendez-vous\" class=\"button-glass\">PLANIFIER UN RENDEZ-VOUS<\/a>\n            <p class=\"contact-direct\">O\u00f9 contactez-nous directement :<br>\n                <a href=\"mailto:info@e-bigfish.com\">info@e-bigfish.com<\/a>\n            <\/p>\n        <\/div>\n    <\/section>\n\n    <!-- ===== SECTION \"COMMENT NOUS CONTACTER\" ===== -->\n    <section id=\"contact\" class=\"tej-page-section tej-contact-section\">\n       <br>\n        <div class=\"tej-section-container\">\n            <header class=\"section-header\">\n                <h2>NOS CONTACTS<\/h2>\n                <h3>Domaines et contacts<\/h3>\n            <\/header>\n            <div class=\"tej-contact-global\">\n                <h4>GLOBAL CONTACT<\/h4>\n                <p><a href=\"http:\/\/www.e-bigfish.com\" target=\"_blank\">www.e-bigfish.com<\/a><br>\n                +33 1 45 62 19 80<br>\n                <a href=\"mailto:info@e-bigfish.com\">info@e-bigfish.com<\/a><\/p>\n            <\/div>\n            <div class=\"tej-contact-grid\">\n                <div class=\"tej-contact-box\">\n                    <h5>EUROPE<\/h5>\n                    <p class=\"section-title\">FRANCE<\/p>\n                    <p><a href=\"mailto:seb@e-bigfish.com\">seb@e-bigfish.com<\/a><\/p>\n                    <p class=\"section-title\">GERMANY<\/p>\n                    <p><a href=\"mailto:nick@e-bigfish.com\">nick@e-bigfish.com<\/a><\/p>\n                    <p class=\"section-title\">POLOGNE<\/p>\n                    <p><a href=\"mailto:aga@e-bigfish.com\">aga@e-bigfish.com<\/a><\/p>\n                <\/div>\n                <div class=\"tej-contact-box\">\n                    <h5>NORTH AMERICA<\/h5>\n                    <p><a href=\"mailto:jp@e-bigfish.com\">jp@e-bigfish.com<\/a><\/p>\n                    <h5>AFRIQUE<\/h5>\n                    <p><a href=\"mailto:julien@e-bigfish.com\">julien@e-bigfish.com<\/a><\/p>\n                    <h5>B52 &#8211; DIGITAL<\/h5>\n                    <p><a href=\"mailto:seb@e-bigfish.com\">seb@e-bigfish.com<\/a><\/p>\n                <\/div>\n                <div class=\"tej-contact-box\">\n                    <h5>DEVELOPPEMENT<\/h5>\n                    <p><a href=\"mailto:abdel@e-bigfish.com\">abdel@e-bigfish.com<\/a><\/p>\n                    <h5>INDIA\/ASIA PACIFIC<\/h5>\n                    <p><a href=\"mailto:nawab@e-bigfish.com\">nawab@e-bigfish.com<\/a><\/p>\n                    <h5>PEOPLE DEVELOPMENT<\/h5>\n                    <p><a href=\"mailto:nick@e-bigfish.com\">nick@e-bigfish.com<\/a><\/p>\n                <\/div>\n                <div class=\"tej-contact-box\">\n                    <h5>TOOLS &#038; METHODS<\/h5>\n                    <p><a href=\"mailto:manu@e-bigfish.com\">manu@e-bigfish.com<\/a><\/p>\n                    <h5>ECOSYSTEM &#038; PARTNERS<\/h5>\n                    <p><a href=\"mailto:nick@e-bigfish.com\">nick@e-bigfish.com<\/a><\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BiG FISH INTERNATIONAL BIG FISH INTERNATIONAL PEOPLE CENTRIC DEVELOPMENT PEOPLE CENTRIC DEVELOPMENT Notre cabinet Ressources Humaines Achats se distingue par une approche unique : le d\u00e9veloppement centr\u00e9 sur les personnes (People Centric Development), pour et par les Achats (P&#038;P). Les personnes sont au c\u0153ur de toute r\u00e9ussite. Elles peuvent surmonter n&rsquo;importe quel d\u00e9fi et atteindre&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - BIG FISH INTERNATIONAL<\/title>\n<meta name=\"description\" content=\"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-bigfish.com\/bigfishint\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - BIG FISH INTERNATIONAL\" \/>\n<meta property=\"og:description\" content=\"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-bigfish.com\/bigfishint\/\" \/>\n<meta property=\"og:site_name\" content=\"BIG FISH INTERNATIONAL\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T14:31:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/\",\"url\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/\",\"name\":\"Accueil - BIG FISH INTERNATIONAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Stick-Man.png\",\"datePublished\":\"2025-09-11T15:54:06+00:00\",\"dateModified\":\"2026-02-09T14:31:21+00:00\",\"description\":\"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Stick-Man.png\",\"contentUrl\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Stick-Man.png\",\"width\":1131,\"height\":997},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/#website\",\"url\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/\",\"name\":\"BIG FISH INTERNATIONAL\",\"description\":\"PEOPLE CENTRIC DEVELOPMENT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-bigfish.com\\\/bigfishint\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - BIG FISH INTERNATIONAL","description":"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-bigfish.com\/bigfishint\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - BIG FISH INTERNATIONAL","og_description":"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.","og_url":"https:\/\/e-bigfish.com\/bigfishint\/","og_site_name":"BIG FISH INTERNATIONAL","article_modified_time":"2026-02-09T14:31:21+00:00","og_image":[{"url":"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-bigfish.com\/bigfishint\/","url":"https:\/\/e-bigfish.com\/bigfishint\/","name":"Accueil - BIG FISH INTERNATIONAL","isPartOf":{"@id":"https:\/\/e-bigfish.com\/bigfishint\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-bigfish.com\/bigfishint\/#primaryimage"},"image":{"@id":"https:\/\/e-bigfish.com\/bigfishint\/#primaryimage"},"thumbnailUrl":"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png","datePublished":"2025-09-11T15:54:06+00:00","dateModified":"2026-02-09T14:31:21+00:00","description":"Transformez la performance de vos \u00e9quipes Achats. Notre cabinet de Ressources Humaines allie expertise m\u00e9tier et approche humaine unique pour des r\u00e9sultats mesurables et durables.","breadcrumb":{"@id":"https:\/\/e-bigfish.com\/bigfishint\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-bigfish.com\/bigfishint\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/e-bigfish.com\/bigfishint\/#primaryimage","url":"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png","contentUrl":"https:\/\/e-bigfish.com\/bigfishint\/wp-content\/uploads\/2025\/09\/Stick-Man.png","width":1131,"height":997},{"@type":"BreadcrumbList","@id":"https:\/\/e-bigfish.com\/bigfishint\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/e-bigfish.com\/bigfishint\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/e-bigfish.com\/bigfishint\/#website","url":"https:\/\/e-bigfish.com\/bigfishint\/","name":"BIG FISH INTERNATIONAL","description":"PEOPLE CENTRIC DEVELOPMENT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-bigfish.com\/bigfishint\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":73,"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":693,"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/pages\/10\/revisions\/693"}],"wp:attachment":[{"href":"https:\/\/e-bigfish.com\/bigfishint\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}